{"id":190,"date":"2018-05-20T12:57:16","date_gmt":"2018-05-20T10:57:16","guid":{"rendered":"http:\/\/asso-catalyse.fr\/?p=190"},"modified":"2021-01-02T19:31:39","modified_gmt":"2021-01-02T18:31:39","slug":"accompagnement-du-projet-de-loasis-de-cintenat","status":"publish","type":"post","link":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/","title":{"rendered":"Accompagnement du projet de l&rsquo;Oasis de Cintenat"},"content":{"rendered":"<p>Nous accompagnons le projet de cr\u00e9ation de l&rsquo;<a href=\"https:\/\/www.sourcemem.org\/fr\/blog-fr\/in-situ\/\">Oasis de Cintenat<\/a>.<\/p>\n<p>Pour l&rsquo;instant nous sommes intervenus en conseil sur les syst\u00e8mes de chauffage, les r\u00e9seaux d&rsquo;eau (potable, pluie, grise, noire) et l&rsquo;organisation g\u00e9n\u00e9rale des flux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous accompagnons le projet de cr\u00e9ation de l&rsquo;Oasis de Cintenat. Pour l&rsquo;instant nous sommes intervenus en conseil sur les syst\u00e8mes de chauffage, les r\u00e9seaux d&rsquo;eau (potable, pluie, grise, noire) et l&rsquo;organisation g\u00e9n\u00e9rale des flux.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[8,6],"class_list":["post-190","post","type-post","status-publish","format-standard","hentry","category-realisations","tag-accompagnement","tag-autonomie-energetique"],"featured_image_urls_v2":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","post-thumbnail":"","one-page-express-full-hd":""},"post_excerpt_stackable_v2":"<p>Nous accompagnons le projet de cr\u00e9ation de l&rsquo;Oasis de Cintenat. Pour l&rsquo;instant nous sommes intervenus en conseil sur les syst\u00e8mes de chauffage, les r\u00e9seaux d&rsquo;eau (potable, pluie, grise, noire) et l&rsquo;organisation g\u00e9n\u00e9rale des flux.<\/p>\n","category_list_v2":"<a href=\"https:\/\/asso-catalyse.fr\/index.php\/category\/realisations\/\" rel=\"category tag\">R\u00e9alisations<\/a>","author_info_v2":{"name":"Catalyse","url":"https:\/\/asso-catalyse.fr\/index.php\/author\/catalyse\/"},"comments_num_v2":"0 commentaire","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accompagnement du projet de l&#039;Oasis de Cintenat &#8902; Association Catalyse<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accompagnement du projet de l&#039;Oasis de Cintenat &#8902; Association Catalyse\" \/>\n<meta property=\"og:description\" content=\"Nous accompagnons le projet de cr\u00e9ation de l&rsquo;Oasis de Cintenat. Pour l&rsquo;instant nous sommes intervenus en conseil sur les syst\u00e8mes de chauffage, les r\u00e9seaux d&rsquo;eau (potable, pluie, grise, noire) et l&rsquo;organisation g\u00e9n\u00e9rale des flux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/\" \/>\n<meta property=\"og:site_name\" content=\"Association Catalyse\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-20T10:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-02T18:31:39+00:00\" \/>\n<meta name=\"author\" content=\"Catalyse\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Catalyse\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/\",\"url\":\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/\",\"name\":\"Accompagnement du projet de l'Oasis de Cintenat &#8902; Association Catalyse\",\"isPartOf\":{\"@id\":\"https:\/\/asso-catalyse.fr\/#website\"},\"datePublished\":\"2018-05-20T10:57:16+00:00\",\"dateModified\":\"2021-01-02T18:31:39+00:00\",\"author\":{\"@id\":\"https:\/\/asso-catalyse.fr\/#\/schema\/person\/e207c7be9bb40203e731d212648f72ab\"},\"breadcrumb\":{\"@id\":\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/asso-catalyse.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Accompagnement du projet de l&rsquo;Oasis de Cintenat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/asso-catalyse.fr\/#website\",\"url\":\"https:\/\/asso-catalyse.fr\/\",\"name\":\"Association Catalyse\",\"description\":\"Autonomie \u00e9nerg\u00e9tique pour le milieu rural\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/asso-catalyse.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/asso-catalyse.fr\/#\/schema\/person\/e207c7be9bb40203e731d212648f72ab\",\"name\":\"Catalyse\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/asso-catalyse.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/647361d78cb116a79c299ce9f2634100?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/647361d78cb116a79c299ce9f2634100?s=96&d=mm&r=g\",\"caption\":\"Catalyse\"},\"url\":\"https:\/\/asso-catalyse.fr\/index.php\/author\/catalyse\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accompagnement du projet de l'Oasis de Cintenat &#8902; Association Catalyse","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/","og_locale":"fr_FR","og_type":"article","og_title":"Accompagnement du projet de l'Oasis de Cintenat &#8902; Association Catalyse","og_description":"Nous accompagnons le projet de cr\u00e9ation de l&rsquo;Oasis de Cintenat. Pour l&rsquo;instant nous sommes intervenus en conseil sur les syst\u00e8mes de chauffage, les r\u00e9seaux d&rsquo;eau (potable, pluie, grise, noire) et l&rsquo;organisation g\u00e9n\u00e9rale des flux.","og_url":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/","og_site_name":"Association Catalyse","article_published_time":"2018-05-20T10:57:16+00:00","article_modified_time":"2021-01-02T18:31:39+00:00","author":"Catalyse","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Catalyse"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/","url":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/","name":"Accompagnement du projet de l'Oasis de Cintenat &#8902; Association Catalyse","isPartOf":{"@id":"https:\/\/asso-catalyse.fr\/#website"},"datePublished":"2018-05-20T10:57:16+00:00","dateModified":"2021-01-02T18:31:39+00:00","author":{"@id":"https:\/\/asso-catalyse.fr\/#\/schema\/person\/e207c7be9bb40203e731d212648f72ab"},"breadcrumb":{"@id":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/asso-catalyse.fr\/index.php\/2018\/05\/20\/accompagnement-du-projet-de-loasis-de-cintenat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asso-catalyse.fr\/"},{"@type":"ListItem","position":2,"name":"Accompagnement du projet de l&rsquo;Oasis de Cintenat"}]},{"@type":"WebSite","@id":"https:\/\/asso-catalyse.fr\/#website","url":"https:\/\/asso-catalyse.fr\/","name":"Association Catalyse","description":"Autonomie \u00e9nerg\u00e9tique pour le milieu rural","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asso-catalyse.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/asso-catalyse.fr\/#\/schema\/person\/e207c7be9bb40203e731d212648f72ab","name":"Catalyse","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asso-catalyse.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/647361d78cb116a79c299ce9f2634100?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/647361d78cb116a79c299ce9f2634100?s=96&d=mm&r=g","caption":"Catalyse"},"url":"https:\/\/asso-catalyse.fr\/index.php\/author\/catalyse\/"}]}},"_links":{"self":[{"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/posts\/190"}],"collection":[{"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/comments?post=190"}],"version-history":[{"count":1,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/posts\/190\/revisions"}],"predecessor-version":[{"id":191,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/posts\/190\/revisions\/191"}],"wp:attachment":[{"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/media?parent=190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/categories?post=190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asso-catalyse.fr\/index.php\/wp-json\/wp\/v2\/tags?post=190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}